{"id":3,"date":"2022-11-05T10:27:38","date_gmt":"2022-11-05T10:27:38","guid":{"rendered":"https:\/\/promopers.com\/?page_id=3"},"modified":"2023-03-02T09:07:49","modified_gmt":"2023-03-02T09:07:49","slug":"privacy","status":"publish","type":"page","link":"https:\/\/promopers.com\/it\/privacy\/","title":{"rendered":"<p>Informativa sulla privacy<\/p>"},"content":{"rendered":"<h2>Protezione dei dati<h2>Informativa sulla privacy<\/h2><p>Il responsabile ai sensi delle leggi sulla protezione dei dati, in particolare del Regolamento generale sulla protezione dei dati dell'UE (DSGVO), \u00e8:<\/p><p>X-Tool Services (Svizzera) AG<br>R\u00fctistrasse 12<br>8952 Schlieren<\/p><p><br>E-mail: purpura@promopers.com<br>Sito web: https:\/\/www.promopers.com\/privacy<\/p><h2>Nota generale<\/h2><p>In base all'articolo 13 della Costituzione federale svizzera e alle disposizioni sulla protezione dei dati della Confederazione svizzera (Legge sulla protezione dei dati, LPD), ogni persona ha il diritto di proteggere la propria privacy e di essere tutelata dall'uso improprio dei propri dati personali. Gli operatori di queste pagine prendono molto sul serio la protezione dei vostri dati personali. Trattiamo i vostri dati personali in modo confidenziale e in conformit\u00e0 alle norme di legge sulla protezione dei dati e alla presente dichiarazione sulla protezione dei dati.<\/p><p>In collaborazione con i nostri fornitori di hosting, cerchiamo di proteggere al meglio i database da accessi non autorizzati, perdita, uso improprio o falsificazione.<\/p><p>Desideriamo sottolineare che la trasmissione di dati su Internet (ad esempio la comunicazione via e-mail) pu\u00f2 presentare lacune nella sicurezza. Non \u00e8 possibile proteggere completamente i dati dall'accesso di terzi.<\/p><p>Utilizzando questo sito web, acconsentite alla raccolta, all'elaborazione e all'utilizzo dei dati come descritto di seguito. Questo sito web pu\u00f2 essere visitato generalmente senza registrazione. Nel corso di questo processo, dati come le pagine richiamate o il nome del file richiamato, la data e l'ora vengono memorizzati sul server a fini statistici senza che questi dati siano direttamente collegati alla vostra persona. I dati personali, in particolare il nome, l'indirizzo o l'indirizzo e-mail, vengono raccolti per quanto possibile su base volontaria. I dati non saranno trasmessi a terzi senza il vostro consenso.<\/p><h2>Trattamento dei dati personali<\/h2><p>I dati personali sono tutte le informazioni relative a una persona identificata o identificabile. L'interessato \u00e8 una persona sulla quale vengono trattati i dati personali. L'elaborazione comprende qualsiasi trattamento dei dati personali, indipendentemente dai mezzi e dalle procedure utilizzati, in particolare l'archiviazione, la divulgazione, l'acquisizione, la cancellazione, la conservazione, la modifica, la distruzione e l'utilizzo dei dati personali.<\/p><p>Trattiamo i dati personali in conformit\u00e0 alla legge svizzera sulla protezione dei dati. Inoltre, trattiamo i dati personali - nella misura e nella misura in cui \u00e8 applicabile il GDPR dell'UE - in base alle seguenti basi giuridiche. trattiamo i dati personali in base alle seguenti basi giuridiche in relazione all'art. 6 comma 1 DSGVO:<\/p><ul>\n<li>lit. a) Trattamento dei dati personali con il consenso dell'interessato.<\/li>\n\n\n\n<li>b) Trattamento dei dati personali per l'adempimento di un contratto con l'interessato e per l'attuazione di misure precontrattuali corrispondenti.<\/li>\n\n\n\n<li>c) trattamento dei dati personali per adempiere a un obbligo legale a cui siamo soggetti ai sensi di qualsiasi legge applicabile dell'UE o di qualsiasi legge applicabile di un paese in cui il GDPR si applica in tutto o in parte.<\/li>\n\n\n\n<li>d) Trattamento dei dati personali al fine di proteggere gli interessi vitali dell'interessato o di un'altra persona fisica.<\/li>\n\n\n\n<li>lit. f) Trattamento dei dati personali per tutelare gli interessi legittimi nostri o di terzi, a condizione che non prevalgano le libert\u00e0 fondamentali, i diritti e gli interessi dell'interessato. Gli interessi legittimi sono in particolare il nostro interesse commerciale a fornire il nostro sito web, la sicurezza delle informazioni, l'applicazione dei nostri diritti legali e il rispetto della legge svizzera.<\/li>\n<\/ul><p>Trattiamo i dati personali per il periodo di tempo necessario per il rispettivo scopo o scopi. In caso di obblighi di conservazione a lungo termine dovuti a obblighi legali o di altro tipo a cui siamo soggetti, limitiamo il trattamento di conseguenza.<\/p><h2>Informativa sulla privacy per i cookie<\/h2><p>Questo sito web utilizza i cookie. Si tratta di piccoli file di testo che consentono di memorizzare informazioni specifiche relative all'utente sul suo terminale durante l'utilizzo del sito web. I cookie consentono, in particolare, di determinare la frequenza di utilizzo e il numero di utenti delle pagine, di analizzare i modelli di comportamento nell'utilizzo delle pagine, ma anche di rendere la nostra offerta pi\u00f9 adatta ai clienti. I cookie rimangono memorizzati oltre la fine di una sessione del browser e possono essere recuperati quando si visita nuovamente il sito. Se non lo desiderate, dovete impostare il vostro browser Internet in modo da rifiutare l'accettazione dei cookie.<\/p><p>Un'obiezione generale all'uso dei cookie per scopi di marketing online pu\u00f2 essere fatta per molti dei servizi, in particolare nel caso del tracciamento, attraverso il sito americano <a href=\"http:\/\/www.aboutads.info\/choices\/\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/www.aboutads.info\/choices\/<\/a> o dalla parte dell'UE <a href=\"http:\/\/www.youronlinechoices.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/www.youronlinechoices.com\/<\/a> essere dichiarati. Inoltre, la memorizzazione dei cookie pu\u00f2 essere ottenuta disattivandoli nelle impostazioni del browser. Si prega di notare che non tutte le funzioni di questa offerta online possono essere utilizzate.<\/p><h2>Informativa sulla privacy per la crittografia SSL\/TLS<\/h2><p>Questo sito web utilizza la crittografia SSL\/TLS per motivi di sicurezza e per proteggere la trasmissione di contenuti riservati, come le richieste di informazioni che ci inviate in qualit\u00e0 di gestore del sito. \u00c8 possibile riconoscere una connessione crittografata dal fatto che la riga dell'indirizzo del browser passa da \"http:\/\/\" a \"https:\/\/\" e dal simbolo del lucchetto nella riga del browser.<\/p><p>Se la crittografia SSL o TLS \u00e8 attivata, i dati che ci trasmettete non possono essere letti da terzi.<\/p><h2>Sicurezza della trasmissione dei dati (senza SSL)<\/h2><p>Si noti che i dati trasmessi tramite una rete aperta come Internet o un servizio di posta elettronica senza crittografia SSL possono essere visualizzati da chiunque. Una connessione non criptata si riconosce dal fatto che nella riga dell'indirizzo del browser compare la scritta \"http:\/\/\" e che nella riga del browser non compare il simbolo del lucchetto. Le informazioni trasmesse su Internet e i contenuti ricevuti online possono essere trasmessi su reti di terzi. Non possiamo garantire la riservatezza delle comunicazioni o dei materiali trasmessi su tali reti aperte o di terzi.<\/p><p>Se comunicate informazioni personali attraverso una rete aperta o di terzi, dovete essere consapevoli del fatto che i vostri dati possono andare persi o che terzi possono potenzialmente accedere a queste informazioni e di conseguenza raccogliere e utilizzare i dati senza il vostro consenso. In molti casi i singoli pacchetti di dati vengono trasmessi in forma criptata, ma non i nomi del mittente e del destinatario. Anche se il mittente e il destinatario risiedono nello stesso Paese, il trasferimento dei dati attraverso tali reti avviene spesso senza controlli anche attraverso Paesi terzi, ossia anche attraverso Paesi che non offrono lo stesso livello di protezione dei dati del vostro Paese di residenza. Non ci assumiamo alcuna responsabilit\u00e0 per la sicurezza dei vostri dati durante la trasmissione via Internet e decliniamo ogni responsabilit\u00e0 per perdite dirette o indirette. Vi chiediamo di utilizzare altri mezzi di comunicazione qualora lo riteniate necessario o ragionevole per motivi di sicurezza.<\/p><p>Nonostante le ampie misure di sicurezza tecniche e organizzative, \u00e8 possibile che i dati vadano persi o che vengano intercettati e\/o manipolati da persone non autorizzate. Per quanto possibile, adottiamo misure di sicurezza tecniche e organizzative adeguate per evitare che ci\u00f2 avvenga all'interno del nostro sistema. Tuttavia, il vostro computer si trova al di fuori del perimetro di sicurezza sotto il nostro controllo. \u00c8 responsabilit\u00e0 dell'utente informarsi sulle precauzioni di sicurezza necessarie e adottare le misure adeguate a questo proposito. In qualit\u00e0 di gestore del sito web, non siamo in alcun modo responsabili di eventuali danni che l'utente potrebbe subire a causa della perdita o della manipolazione dei dati.<\/p><p>I dati forniti dall'utente nei moduli online possono essere trasmessi a terzi incaricati per l'elaborazione degli ordini e possono essere visualizzati ed eventualmente elaborati da questi ultimi.<\/p><h2>Informativa sulla privacy per i file di log del server<\/h2><p>Il provider di questo sito web raccoglie e memorizza automaticamente le informazioni nei cosiddetti file di log del server, che il vostro browser ci trasmette automaticamente. Questi sono:<\/p><ul>\n<li>Tipo e versione del browser<\/li>\n\n\n\n<li>Sistema operativo utilizzato<\/li>\n\n\n\n<li>URL di riferimento<\/li>\n\n\n\n<li>Nome host del computer di accesso<\/li>\n\n\n\n<li>Ora della richiesta del server<\/li>\n<\/ul><p>Questi dati non possono essere assegnati a persone specifiche. Questi dati non vengono uniti ad altre fonti di dati. Ci riserviamo il diritto di controllare questi dati a posteriori se veniamo a conoscenza di indizi concreti di utilizzo illegale.<\/p><h2>Servizi di terze parti<\/h2><p>Questo sito web pu\u00f2 utilizzare Google Maps per incorporare mappe, Google Invisible reCAPTCHA per la protezione da bot e spam e YouTube per incorporare video.<\/p><p>Questi servizi dell'americana Google LLC utilizzano, tra l'altro, i cookie e, di conseguenza, i dati vengono trasmessi a Google negli Stati Uniti, anche se si presume che in questo contesto non avvenga alcun tracciamento personale esclusivamente attraverso l'utilizzo del nostro sito web.<\/p><p>Google si \u00e8 impegnata a garantire un'adeguata protezione dei dati in conformit\u00e0 con gli Scudi per la privacy USA-Europa e USA-Svizzera.<\/p><p>Ulteriori informazioni sono disponibili nella sezione <a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noreferrer noopener\">Informativa sulla privacy di Google<\/a>.<\/p><h2>Informativa sulla privacy per il modulo di contatto<\/h2><p>Se ci inviate richieste di informazioni tramite il modulo di contatto, i vostri dati del modulo di richiesta, compresi i dati di contatto che ci avete fornito, saranno memorizzati da noi allo scopo di elaborare la richiesta e in caso di domande successive. Non trasmettiamo questi dati senza il vostro consenso.<\/p><h2>Informativa sulla privacy per i dati della newsletter<\/h2><p>Se desiderate ricevere la newsletter offerta su questo sito web, vi chiediamo un indirizzo e-mail e informazioni che ci permettano di verificare che siete i proprietari dell'indirizzo e-mail fornito e che accettate di ricevere la newsletter. Non verranno raccolti altri dati. Utilizziamo questi dati esclusivamente per l'invio delle informazioni richieste e non li trasmettiamo a terzi.<\/p><p>Potete revocare il vostro consenso alla memorizzazione dei dati, dell'indirizzo e-mail e del loro utilizzo per l'invio della newsletter in qualsiasi momento, ad esempio tramite il \"link di cancellazione\" presente nella newsletter.<\/p><h2>Informativa sulla privacy per la funzione commenti di questo sito web<\/h2><p>Per quanto riguarda la funzione di commento su questo sito web, oltre al vostro commento, verranno memorizzati i dettagli relativi alla data di creazione del commento, il vostro indirizzo e-mail e, se non postate in forma anonima, il nome utente che avete scelto.<\/p><p><em>Memorizzazione dell'indirizzo IP<\/em><\/p><p>La nostra funzione di commento memorizza gli indirizzi IP degli utenti che pubblicano commenti. Poich\u00e9 non controlliamo i commenti sul nostro sito prima che vengano attivati, abbiamo bisogno di questi dati per poter prendere provvedimenti contro l'autore in caso di violazioni legali come insulti o propaganda.<\/p><p><em>Iscriviti ai commenti<\/em><\/p><p>Come utente del sito, \u00e8 possibile iscriversi ai commenti dopo essersi registrati. Riceverete un'e-mail di conferma per verificare che siate i proprietari dell'indirizzo e-mail fornito. \u00c8 possibile annullare l'iscrizione a questa funzione in qualsiasi momento tramite un link contenuto nelle e-mail informative.<\/p><h2>Diritti degli interessati<\/h2><p><strong>Diritto alla conferma<\/strong><\/p><p>Ogni soggetto interessato ha il diritto di chiedere al gestore del sito web la conferma che i dati personali che lo riguardano siano trattati. Se si desidera esercitare questo diritto di conferma, \u00e8 possibile contattare il responsabile della protezione dei dati in qualsiasi momento.<\/p><p><strong>Diritto all'informazione<\/strong><\/p><p>Ogni persona interessata dal trattamento dei dati personali ha il diritto di ricevere gratuitamente dal gestore di questo sito web informazioni sui dati personali memorizzati che la riguardano e una copia di tali informazioni in qualsiasi momento. Inoltre, possono essere fornite informazioni sui seguenti dati, se applicabili:<\/p><ul>\n<li>le finalit\u00e0 del trattamento<\/li>\n\n\n\n<li>le categorie di dati personali trattati<\/li>\n\n\n\n<li>i destinatari a cui sono stati o saranno comunicati i dati personali<\/li>\n\n\n\n<li>se possibile, la durata prevista per la conservazione dei dati personali o, se ci\u00f2 non \u00e8 possibile, i criteri per determinare tale durata<\/li>\n\n\n\n<li>l'esistenza del diritto di ottenere la rettifica o la cancellazione dei dati personali che li riguardano o di ottenere la limitazione del trattamento da parte del responsabile del trattamento o il diritto di opporsi a tale trattamento<\/li>\n\n\n\n<li>l'esistenza di un diritto di ricorso a un'autorit\u00e0 di vigilanza<\/li>\n\n\n\n<li>se i dati personali non sono stati raccolti dall'interessato: Tutte le informazioni disponibili sull'origine dei dati<\/li>\n<\/ul><p>Inoltre, l'interessato ha il diritto di essere informato se i dati personali sono stati trasferiti a un paese terzo o a un'organizzazione internazionale. In tal caso, l'interessato ha anche il diritto di ottenere informazioni sulle garanzie appropriate in relazione al trasferimento.<\/p><p>Se desiderate avvalervi di questo diritto all'informazione, potete contattare il nostro responsabile della protezione dei dati in qualsiasi momento.<\/p><p><strong>Diritto di rettifica<\/strong><\/p><p>Chiunque sia interessato dal trattamento dei dati personali ha il diritto di ottenere la rettifica senza ritardo dei dati personali inesatti che lo riguardano. L'interessato ha inoltre il diritto di ottenere, tenuto conto delle finalit\u00e0 del trattamento, il completamento di eventuali dati personali incompleti, anche mediante una dichiarazione integrativa.<\/p><p>Se desiderate avvalervi di questo diritto di rettifica, potete contattare il nostro responsabile della protezione dei dati in qualsiasi momento.<\/p><p><strong>Diritto alla cancellazione (diritto all'oblio)<\/strong><\/p><p>Chiunque sia interessato dal trattamento dei dati personali ha il diritto di ottenere dal responsabile del trattamento di questo sito web la cancellazione immediata dei dati personali che lo riguardano, qualora si applichi uno dei seguenti motivi e nella misura in cui il trattamento non sia necessario:<\/p><ul>\n<li>I dati personali sono stati raccolti o altrimenti trattati per finalit\u00e0 per le quali non sono pi\u00f9 necessari<\/li>\n\n\n\n<li>L'interessato ritira il consenso su cui si basava il trattamento e non esiste un altro fondamento giuridico per il trattamento<\/li>\n\n\n\n<li>L'interessato si oppone al trattamento per motivi connessi alla sua situazione particolare e non sussistono motivi legittimi prevalenti per il trattamento, oppure si oppone al trattamento in caso di marketing diretto e relativa profilazione.<\/li>\n\n\n\n<li>I dati personali sono stati trattati illegalmente<\/li>\n\n\n\n<li>La cancellazione dei dati personali \u00e8 necessaria per l'adempimento di un obbligo legale ai sensi del diritto dell'Unione o degli Stati membri a cui il responsabile del trattamento \u00e8 soggetto<\/li>\n\n\n\n<li>I dati personali sono stati raccolti in relazione a servizi della societ\u00e0 dell'informazione offerti direttamente a un bambino.<\/li>\n<\/ul><p>Se si applica uno dei motivi di cui sopra e si desidera richiedere la cancellazione dei dati personali memorizzati dal gestore di questo sito web, \u00e8 possibile contattare il nostro responsabile della protezione dei dati in qualsiasi momento. Il responsabile della protezione dei dati di questo sito web provveder\u00e0 a soddisfare immediatamente la richiesta di cancellazione.<\/p><p><strong>Diritto di limitare il trattamento<\/strong><\/p><p>Qualsiasi persona interessata dal trattamento dei dati personali ha il diritto di ottenere dal responsabile del trattamento di questo sito web la limitazione del trattamento se \u00e8 soddisfatta una delle seguenti condizioni:<\/p><ul>\n<li>L'esattezza dei dati personali \u00e8 contestata dall'interessato per un periodo che consenta al responsabile del trattamento di verificare l'esattezza dei dati personali.<\/li>\n\n\n\n<li>Il trattamento \u00e8 illecito, l'interessato si oppone alla cancellazione dei dati personali e chiede invece la limitazione dell'uso dei dati personali.<\/li>\n\n\n\n<li>Il responsabile del trattamento non ha pi\u00f9 bisogno dei dati personali per le finalit\u00e0 del trattamento, ma l'interessato ne ha bisogno per l'istituzione, l'esercizio o la difesa di diritti legali.<\/li>\n\n\n\n<li>L'interessato si \u00e8 opposto al trattamento per motivi connessi alla sua situazione particolare e non \u00e8 ancora chiaro se i legittimi interessi del responsabile del trattamento prevalgano su quelli dell'interessato.<\/li>\n<\/ul><p>Se una delle condizioni di cui sopra \u00e8 soddisfatta e si desidera richiedere la restrizione dei dati personali memorizzati dal gestore di questo sito web, \u00e8 possibile contattare il nostro responsabile della protezione dei dati in qualsiasi momento. Il responsabile della protezione dei dati di questo sito web provveder\u00e0 alla limitazione del trattamento.<\/p><p><strong>Diritto alla portabilit\u00e0 dei dati<\/strong><\/p><p>Ogni persona interessata dal trattamento dei dati personali ha il diritto di ricevere i dati personali che la riguardano in un formato strutturato, comune e leggibile a macchina. Ha inoltre il diritto di ottenere il trasferimento di tali dati a un altro titolare del trattamento, se sono soddisfatti i requisiti di legge.<\/p><p>Inoltre, l'interessato ha il diritto di ottenere il trasferimento diretto dei dati personali da un responsabile del trattamento a un altro responsabile del trattamento, ove tecnicamente fattibile e a condizione che ci\u00f2 non pregiudichi i diritti e le libert\u00e0 di altre persone.<\/p><p>Per far valere il diritto alla portabilit\u00e0 dei dati, potete contattare in qualsiasi momento il responsabile della protezione dei dati nominato dal gestore di questo sito web.<\/p><p><strong>Diritto di opposizione<\/strong><\/p><p>Qualsiasi persona interessata dal trattamento dei dati personali ha il diritto di opporsi in qualsiasi momento, per motivi legati alla sua situazione particolare, al trattamento dei dati personali che la riguardano.<\/p><p>Il gestore di questo sito web non elaborer\u00e0 pi\u00f9 i dati personali in caso di obiezione, a meno che non si possano dimostrare motivi legittimi impellenti per l'elaborazione che prevalgono sugli interessi, i diritti e le libert\u00e0 dell'interessato, o se l'elaborazione serve per l'affermazione, l'esercizio o la difesa di rivendicazioni legali.<\/p><p>Per esercitare il vostro diritto di opposizione, potete contattare direttamente il responsabile della protezione dei dati di questo sito web.<\/p><p><strong>Diritto di revoca del consenso ai sensi della legge sulla protezione dei dati personali<\/strong><\/p><p>Ogni persona interessata dal trattamento dei dati personali ha il diritto di revocare in qualsiasi momento il consenso dato al trattamento dei dati personali.<\/p><p>Se desiderate esercitare il diritto di revoca del consenso, potete contattare il nostro responsabile della protezione dei dati in qualsiasi momento.<\/p><h2>Informativa sulla privacy per le mail pubblicitarie di Contraddizione<\/h2><p>\u00c8 vietato l'utilizzo dei dati di contatto pubblicati nell'ambito dell'obbligo di imprinting per l'invio di materiale pubblicitario e informativo non espressamente richiesto. I gestori delle pagine si riservano espressamente il diritto di intraprendere azioni legali in caso di invio non richiesto di informazioni pubblicitarie, come ad esempio e-mail di spam.<\/p><h2>Servizi con costi<\/h2><p>Per la fornitura di servizi a pagamento, richiediamo ulteriori dati, come quelli relativi al pagamento, per poter eseguire l'ordine. Conserviamo questi dati nei nostri sistemi fino alla scadenza dei periodi di conservazione previsti dalla legge.<\/p><h2>Google AdWords<\/h2><p>Questo sito web utilizza il Conversion Tracking di Google. Se avete raggiunto il nostro sito web tramite un annuncio pubblicitario di Google, Google Adwords imposter\u00e0 un cookie sul vostro computer. Il cookie di conversion tracking viene impostato quando un utente fa clic su un annuncio pubblicitario pubblicato da Google. Questi cookie perdono la loro validit\u00e0 dopo 30 giorni e non vengono utilizzati per l'identificazione personale. Se l'utente visita determinate pagine del nostro sito web e il cookie non \u00e8 ancora scaduto, noi e Google possiamo riconoscere che l'utente ha fatto clic sull'annuncio ed \u00e8 stato reindirizzato a questa pagina. Ogni cliente di Google AdWords riceve un cookie diverso. I cookie non possono quindi essere tracciati tra i siti web dei clienti AdWords. Le informazioni ottenute tramite il cookie di conversione vengono utilizzate per creare statistiche di conversione per i clienti AdWords che hanno optato per il monitoraggio delle conversioni. I clienti vengono a conoscenza del numero totale di utenti che hanno fatto clic sul loro annuncio e sono stati reindirizzati a una pagina con un tag di monitoraggio delle conversioni. Tuttavia, non ricevono alcuna informazione che possa essere utilizzata per identificare personalmente gli utenti.<\/p><p>Se non desiderate partecipare al tracciamento, potete rifiutare l'impostazione di un cookie necessario a tal fine, ad esempio mediante un'impostazione del browser che disattivi in generale l'impostazione automatica dei cookie o impostando il vostro browser in modo tale da bloccare i cookie del dominio \"googleleadservices.com\".<\/p><p>Si prega di notare che non si devono cancellare i cookie di opt-out finch\u00e9 non si desidera che vengano registrati i dati di misurazione. Se avete cancellato tutti i cookie nel browser, dovete impostare nuovamente il relativo cookie di opt-out.<\/p><h2>Utilizzo di Google reCAPTCHA<\/h2><p>Questo sito web utilizza il servizio reCAPTCHA di Google Ireland Limited (Gordon House, Barrow Street Dublin 4, Irlanda ?Google?). Lo scopo dell'interrogazione \u00e8 quello di distinguere se l'input viene effettuato da un essere umano o da un'elaborazione automatica. L'interrogazione comprende l'invio a Google dell'indirizzo IP e di qualsiasi altro dato richiesto da Google per il servizio reCAPTCHA. A tal fine, il vostro input viene trasmesso a Google e ivi ulteriormente utilizzato. Tuttavia, il vostro indirizzo IP viene preventivamente abbreviato da Google all'interno degli Stati membri dell'Unione Europea o in altri Stati contraenti dell'Accordo sullo Spazio Economico Europeo. Solo in casi eccezionali l'indirizzo IP completo verr\u00e0 trasmesso a un server di Google negli USA e l\u00ec abbreviato. Su incarico del gestore di questo sito web, Google utilizzer\u00e0 queste informazioni per valutare l'utilizzo di questo servizio da parte dell'utente. L'indirizzo IP trasmesso dal vostro browser nell'ambito di reCaptcha non verr\u00e0 unito ad altri dati di Google. I vostri dati potrebbero essere trasmessi anche negli Stati Uniti. Per il trasferimento dei dati negli Stati Uniti esiste una decisione di adeguatezza della Commissione europea, il Privacy Shield. Google aderisce al Privacy Shield e si \u00e8 assoggettata ai suoi requisiti. Facendo clic sulla domanda, acconsentite al trattamento dei vostri dati. Il trattamento si basa sull'art. 6 (1) lit. a DSGVO con il vostro consenso. Potete revocare il vostro consenso in qualsiasi momento, senza che ci\u00f2 influisca sulla legittimit\u00e0 del trattamento effettuato sulla base del consenso fino alla revoca.<\/p><p>Ulteriori informazioni su Google reCAPTCHA e sulla relativa informativa sulla privacy sono disponibili all'indirizzo: <a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/policies.google.com\/privacy?hl=de<\/a><\/p><h2>Informativa sulla privacy per gli annunci di Google<\/h2><p>Questo sito web utilizza lo strumento di marketing online Google Ads di Google (\"Google Ads\"). Google Ads utilizza i cookie per pubblicare annunci pertinenti per gli utenti, per migliorare i rapporti sulle prestazioni delle campagne o per evitare che un utente veda gli stessi annunci pi\u00f9 di una volta. Google utilizza un ID cookie per registrare quali annunci vengono visualizzati in quale browser e pu\u00f2 quindi impedire che vengano visualizzati pi\u00f9 di una volta. Inoltre, Google Ads pu\u00f2 utilizzare gli ID dei cookie per registrare le cosiddette conversioni correlate alle richieste di annunci. Ci\u00f2 avviene, ad esempio, quando un utente vede un annuncio di Google Ads e successivamente richiama il sito web dell'inserzionista con lo stesso browser e vi acquista qualcosa. Secondo Google, i cookie di Google Ads non contengono informazioni personali.<\/p><p>Grazie agli strumenti di marketing utilizzati, il vostro browser stabilisce automaticamente una connessione diretta con il server di Google. Integrando Google Ads, Google riceve l'informazione che avete richiamato la parte corrispondente del nostro sito web o che avete cliccato su uno dei nostri annunci. Se siete registrati a un servizio Google, Google pu\u00f2 assegnare la visita al vostro account. Anche se non siete registrati con Google o non avete effettuato il login, \u00e8 possibile che Google ottenga e memorizzi il vostro indirizzo IP.<\/p><p>\u00c8 possibile impedire la partecipazione a questo processo di tracciamento in vari modi:<\/p><ul>\n<li>regolando di conseguenza il software del vostro browser; in particolare, la soppressione dei cookie di terze parti vi impedir\u00e0 di ricevere annunci di terze parti;<\/li>\n\n\n\n<li>disabilitando i cookie di monitoraggio delle conversioni impostando il browser in modo da bloccare i cookie provenienti dal dominio \"www.googleadservices.com\", <a href=\"https:\/\/adssettings.google.com\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/adssettings.google.com<\/a>, per cui questa impostazione viene cancellata quando si eliminano i cookie;<\/li>\n\n\n\n<li>disattivando gli annunci basati sugli interessi dei fornitori che fanno parte della campagna di autoregolamentazione \"Informazioni sugli annunci\" tramite il link <a href=\"http:\/\/www.aboutads.info\/choices\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.aboutads.info\/choices<\/a>, per cui questa impostazione viene cancellata quando si eliminano i cookie;<\/li>\n\n\n\n<li>disattivandolo definitivamente nei browser Firefox, Internet Explorer o Google Chrome al link <a href=\"http:\/\/www.google.com\/settings\/ads\/plugin\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.google.com\/settings\/ads\/plugin<\/a>. Desideriamo sottolineare che in questo caso potreste non essere in grado di utilizzare appieno tutte le funzioni di questo sito web.<\/li>\n<\/ul><p>La base giuridica per il trattamento dei vostri dati \u00e8 la ponderazione degli interessi, in base alla quale il trattamento dei vostri dati personali sopra descritto non \u00e8 contrastato da alcun interesse prevalente da parte vostra (art. 6 (1) frase 1 lit. f DSGVO). Potete ottenere ulteriori informazioni su Google Ads da Google all'indirizzo <a href=\"https:\/\/ads.google.com\/intl\/de_DE\/home\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/ads.google.com\/intl\/de_DE\/home\/<\/a>e sulla protezione dei dati di Google in generale: <a href=\"https:\/\/www.google.de\/intl\/de\/policies\/privacy\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.google.de\/intl\/de\/policies\/privacy<\/a>. In alternativa, \u00e8 possibile visitare il sito Web della Network Advertising Initiative (NAI) all'indirizzo <a href=\"http:\/\/www.networkadvertising.org\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.networkadvertising.org<\/a> visita<\/p><h2>Google Tag Manager<\/h2><p>Google Tag Manager \u00e8 una soluzione con la quale possiamo gestire i cosiddetti tag dei siti web tramite un'interfaccia e integrare cos\u00ec, ad esempio, Google Analytics e altri servizi di marketing di Google nella nostra offerta online. Il tag manager stesso, che implementa i tag, non tratta alcun dato personale degli utenti. Per quanto riguarda l'elaborazione dei dati personali degli utenti, si rimanda alle seguenti informazioni sui servizi di Google. Linee guida per l'utilizzo: <a href=\"https:\/\/www.google.com\/intl\/de\/tagmanager\/use-policy.html\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.google.com\/intl\/de\/tagmanager\/use-policy.html<\/a>.<\/p><h2>Newsletter? Mailchimp<\/h2><p>La newsletter viene inviata utilizzando il fornitore di servizi di mailing MailChimp, una piattaforma di invio di newsletter del fornitore statunitense Rocket Science Group, LLC, 675 Ponce De Leon Ave NE #5000, Atlanta, GA 30308, USA. \u00c8 possibile leggere l'informativa sulla privacy del fornitore di servizi di mailing all'indirizzo <a href=\"https:\/\/mailchimp.com\/legal\/privacy\/\" target=\"_blank\" rel=\"noreferrer noopener\">qui<\/a> vista. The Rocket Science Group LLC d\/b\/a MailChimp \u00e8 certificato ai sensi dell'accordo Privacy Shield e offre quindi una garanzia di conformit\u00e0 al livello europeo di protezione dei dati (<a href=\"https:\/\/www.privacyshield.gov\/participant?id=a2zt0000000TO6hAAG&amp;status=Active&amp;t=1\" target=\"_blank\" rel=\"noreferrer noopener\">PrivacyShield<\/a>). Il fornitore di servizi di spedizione viene utilizzato sulla base dei nostri interessi legittimi ai sensi dell'art. 6 comma 1 lett. f DSGVO e di un accordo di elaborazione del contratto ai sensi dell'art. 28 comma 3 frase 1 DSGVO.<\/p><p>Il fornitore di servizi di spedizione pu\u00f2 utilizzare i dati dei destinatari in forma pseudonima, ossia senza attribuirli a un utente, per ottimizzare o migliorare i propri servizi, ad esempio per ottimizzare tecnicamente l'invio e la presentazione della newsletter o per scopi statistici. Tuttavia, il fornitore di servizi di spedizione non utilizza i dati dei destinatari delle nostre newsletter per scrivere a loro stessi o per trasmettere i dati a terzi.<\/p><h2>Conferenze audio e video<\/h2><p>Utilizziamo servizi di audio e videoconferenza per comunicare con i nostri utenti e con altri. In particolare, possiamo utilizzarli per conferenze audio e video, riunioni virtuali e formazione come i webinar.<\/p><p>Utilizziamo solo servizi per i quali \u00e8 garantito un livello adeguato di protezione dei dati. Oltre alla presente informativa sulla privacy, si applicano anche i termini e le condizioni dei servizi utilizzati, come le condizioni d'uso o le dichiarazioni sulla privacy.<\/p><p>Utilizziamo in particolare <strong>Zoom<\/strong>Zoom garantisce inoltre i diritti previsti dal Regolamento generale europeo sulla protezione dei dati (GDPR) agli utenti in Svizzera. Per ulteriori informazioni sulla natura, l'ambito e lo scopo del trattamento dei dati, consultare il documento <a href=\"https:\/\/zoom.us\/de-de\/privacy.html\" target=\"_blank\" rel=\"noreferrer noopener\">Informativa sulla privacy<\/a> e sul <a href=\"https:\/\/zoom.us\/docs\/de-de\/privacy-and-legal.html\" target=\"_blank\" rel=\"noreferrer noopener\">Pagina \"Disposizioni legali e protezione dei dati<\/a> ciascuno da Zoom.<\/p><h2>Informativa sulla privacy per YouTube<\/h2><p>Le funzioni del servizio \"YouTube\" sono integrate in questo sito web. \"YouTube\" \u00e8 di propriet\u00e0 di Google Ireland Limited, una societ\u00e0 costituita e gestita secondo le leggi irlandesi con sede legale in Gordon House, Barrow Street, Dublino 4, Irlanda, che gestisce i servizi nello Spazio economico europeo e in Svizzera.<\/p><p>L'accordo legale con \"YouTube\" consiste nei termini e nelle condizioni che si trovano al seguente link: <a href=\"https:\/\/www.youtube.com\/static?gl=DE&amp;template=terms&amp;hl=de\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.youtube.com\/static?gl=de&amp;template=terms&amp;hl=de<\/a>. Le presenti Condizioni costituiscono un accordo legalmente vincolante tra l'utente e \"YouTube\" in merito all'utilizzo dei Servizi. L'informativa sulla privacy di Google spiega come YouTube tratta e protegge i dati personali dell'utente quando utilizza il servizio.<\/p><h2>Servizi di agenzia<\/h2><p>Trattiamo i dati dei nostri clienti in conformit\u00e0 con le norme sulla protezione dei dati del governo federale (legge sulla protezione dei dati, DSG) e con l'EU-DSGVO nell'ambito delle nostre prestazioni contrattuali.<\/p><p>A tal fine trattiamo dati di inventario (ad es. dati anagrafici dei clienti, come nomi o indirizzi), dati di contatto (ad es. e-mail, numeri di telefono), dati di contenuto (ad es. inserimenti di testo, ecc.), dati contrattuali (ad es. oggetto del contratto, durata), dati di pagamento (ad es. coordinate bancarie, cronologia dei pagamenti), dati di utilizzo e metadati (ad es. nel contesto della valutazione e della misurazione del successo delle misure di marketing). I soggetti interessati sono i nostri clienti, le parti interessate e i loro clienti, utenti, visitatori del sito web o dipendenti, nonch\u00e9 terzi. Lo scopo del trattamento \u00e8 la fornitura di servizi contrattuali, la fatturazione e il nostro servizio clienti. La base giuridica del trattamento \u00e8 costituita dall'art. 6 cpv. 1 lett. b DSGVO (prestazioni contrattuali), dall'art. 6 cpv. 1 lett. f DSGVO (analisi, statistiche, ottimizzazione, misure di sicurezza). Trattiamo i dati necessari per la giustificazione e l'adempimento delle prestazioni contrattuali e segnaliamo la necessit\u00e0 della loro divulgazione. La divulgazione a soggetti esterni avviene solo se necessaria nel contesto di un ordine. Quando elaboriamo i dati fornitici nell'ambito di un ordine, agiamo in conformit\u00e0 alle istruzioni del cliente e ai requisiti legali di un trattamento commissionato ai sensi dell'art. 28 DSGVO e non elaboriamo i dati per scopi diversi da quelli specificati nell'ordine.<\/p><p>Cancelliamo i dati dopo la scadenza della garanzia legale e di obblighi analoghi. La necessit\u00e0 di conservare i dati viene verificata a intervalli irregolari. Nel caso di obblighi di archiviazione previsti dalla legge, la cancellazione avviene dopo la loro scadenza. Nel caso di dati comunicati dal cliente nell'ambito di un ordine, li cancelliamo in conformit\u00e0 alle specifiche dell'ordine, in linea di principio dopo la fine dell'ordine.<\/p><h2>Copyright<\/h2><p>I diritti d'autore e tutti gli altri diritti sui contenuti, le immagini, le foto o altri file presenti sul sito web appartengono esclusivamente al gestore di questo sito web o ai titolari dei diritti specificamente indicati. Per la riproduzione di tutti i file \u00e8 necessario ottenere preventivamente il consenso scritto del titolare del copyright.<\/p><p>Chiunque commetta una violazione del copyright senza il consenso del rispettivo detentore dei diritti pu\u00f2 essere perseguito ed eventualmente risarcito.<\/p><h2>Esclusione di responsabilit\u00e0 generale<\/h2><p>Tutte le informazioni presenti sul nostro sito web sono state attentamente controllate. Ci impegniamo al massimo per garantire che le informazioni fornite siano aggiornate, corrette e complete. Tuttavia, non \u00e8 possibile escludere completamente il verificarsi di errori, per cui non possiamo garantire la completezza, la correttezza e l'attualit\u00e0 delle informazioni, comprese quelle giornalistiche ed editoriali. Le richieste di responsabilit\u00e0 per danni causati dall'uso delle informazioni fornite, comprese quelle incomplete o errate, saranno pertanto respinte.<\/p><p>L'editore pu\u00f2 modificare o eliminare testi a propria discrezione e senza preavviso e non \u00e8 obbligato ad aggiornare i contenuti di questo sito web. L'uso o l'accesso a questo sito web \u00e8 a rischio e pericolo del visitatore. L'editore, i suoi clienti o i suoi partner non sono responsabili di alcun danno, come ad esempio danni diretti, indiretti, accidentali, da determinare in anticipo o danni conseguenti, che sono presumibilmente causati dalla visita di questo sito web, e di conseguenza non accettano alcuna responsabilit\u00e0 per questo.<\/p><p>L'editore non si assume inoltre alcuna responsabilit\u00e0 per il contenuto e la disponibilit\u00e0 di siti web di terzi a cui si pu\u00f2 accedere tramite link esterni presenti su questo sito. I gestori dei siti collegati sono esclusivamente responsabili dei loro contenuti. L'editore prende quindi espressamente le distanze da tutti i contenuti di terzi che possono essere rilevanti ai sensi del diritto penale o della responsabilit\u00e0 civile o che possono offendere il buon costume.<\/p><h2>Cambiamenti<\/h2><p>La presente informativa sulla privacy pu\u00f2 essere modificata in qualsiasi momento senza preavviso. Si applicher\u00e0 la versione attuale pubblicata sul nostro sito web. Se la dichiarazione sulla protezione dei dati \u00e8 parte di un accordo con voi, in caso di aggiornamento vi informeremo della modifica via e-mail o con altri mezzi adeguati.<\/p><h2>Domande al responsabile della protezione dei dati<\/h2><p>Se avete domande sulla protezione dei dati, scriveteci via e-mail o contattate direttamente la persona della nostra organizzazione responsabile della protezione dei dati indicata all'inizio di questa informativa sulla privacy.<\/p><p>Schlieren, 01.03.2023<\/p><\/h2>","protected":false},"excerpt":{"rendered":"<p>Dichiarazione sulla protezione dei dati L'ente responsabile ai sensi delle leggi sulla protezione dei dati, in particolare del Regolamento generale sulla protezione dei dati dell'UE (GDPR), \u00e8: X-Tool Services (Schweiz) AGR\u00fctistrasse 128952 Schlieren E-Mail: purpura@promopers.comWebsite: https:\/\/www.promopers.com\/privacy Informazioni generali In base all'articolo 13 della Costituzione federale svizzera e alle disposizioni sulla protezione dei dati della Confederazione svizzera (Legge sulla protezione dei dati, LPD), ogni persona ha il diritto alla protezione della propria privacy e alla protezione contro l'uso improprio dei propri dati personali. ... <p class=\"link-more\"><a href=\"https:\/\/promopers.com\/it\/privacy\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> \"Informativa sulla privacy<\/span><\/a><\/p><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Privacy Policy - X-Tool Services (Schweiz) AG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/promopers.com\/it\/privacy\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy Policy - X-Tool Services (Schweiz) AG\" \/>\n<meta property=\"og:description\" content=\"Datenschutz Datenschutzerkl\u00e4rung Verantwortliche Stelle im Sinne der Datenschutzgesetze, insbesondere der EU-Datenschutzgrundverordnung (DSGVO), ist: X-Tool Services (Schweiz) AGR\u00fctistrasse 128952 Schlieren E-Mail: purpura@promopers.comWebsite: https:\/\/www.promopers.com\/privacy Allgemeiner Hinweis Gest\u00fctzt auf Artikel 13 der schweizerischen Bundesverfassung und den datenschutzrechtlichen Bestimmungen des Bundes (Datenschutzgesetz, DSG) hat jede Person Anspruch auf Schutz ihrer Privatsph\u00e4re sowie auf Schutz vor Missbrauch ihrer pers\u00f6nlichen Daten. &hellip; Leggi tutto &quot;Privacy Policy&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/promopers.com\/it\/privacy\/\" \/>\n<meta property=\"og:site_name\" content=\"X-Tool Services (Schweiz) AG\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/promotionspersonal\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-02T09:07:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"20 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/promopers.com\/privacy\/\",\"url\":\"https:\/\/promopers.com\/privacy\/\",\"name\":\"Privacy Policy - X-Tool Services (Schweiz) AG\",\"isPartOf\":{\"@id\":\"https:\/\/promopers.com\/#website\"},\"datePublished\":\"2022-11-05T10:27:38+00:00\",\"dateModified\":\"2023-03-02T09:07:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/promopers.com\/privacy\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/promopers.com\/privacy\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/promopers.com\/privacy\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/promopers.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/promopers.com\/#website\",\"url\":\"https:\/\/promopers.com\/\",\"name\":\"X-Tool Services (Schweiz) AG\",\"description\":\"Staff Solutions since 1999\",\"publisher\":{\"@id\":\"https:\/\/promopers.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/promopers.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/promopers.com\/#organization\",\"name\":\"promoPers\",\"url\":\"https:\/\/promopers.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/promopers.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/promopers.com\/wp-content\/uploads\/2022\/11\/logo.png\",\"contentUrl\":\"https:\/\/promopers.com\/wp-content\/uploads\/2022\/11\/logo.png\",\"width\":62,\"height\":80,\"caption\":\"promoPers\"},\"image\":{\"@id\":\"https:\/\/promopers.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/promotionspersonal\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy Policy - X-Tool Services (Schweiz) AG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/promopers.com\/it\/privacy\/","og_locale":"it_IT","og_type":"article","og_title":"Privacy Policy - X-Tool Services (Schweiz) AG","og_description":"Datenschutz Datenschutzerkl\u00e4rung Verantwortliche Stelle im Sinne der Datenschutzgesetze, insbesondere der EU-Datenschutzgrundverordnung (DSGVO), ist: X-Tool Services (Schweiz) AGR\u00fctistrasse 128952 Schlieren E-Mail: purpura@promopers.comWebsite: https:\/\/www.promopers.com\/privacy Allgemeiner Hinweis Gest\u00fctzt auf Artikel 13 der schweizerischen Bundesverfassung und den datenschutzrechtlichen Bestimmungen des Bundes (Datenschutzgesetz, DSG) hat jede Person Anspruch auf Schutz ihrer Privatsph\u00e4re sowie auf Schutz vor Missbrauch ihrer pers\u00f6nlichen Daten. &hellip; Leggi tutto \"Privacy Policy\"","og_url":"https:\/\/promopers.com\/it\/privacy\/","og_site_name":"X-Tool Services (Schweiz) AG","article_publisher":"https:\/\/www.facebook.com\/promotionspersonal\/","article_modified_time":"2023-03-02T09:07:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"20 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/promopers.com\/privacy\/","url":"https:\/\/promopers.com\/privacy\/","name":"Privacy Policy - X-Tool Services (Schweiz) AG","isPartOf":{"@id":"https:\/\/promopers.com\/#website"},"datePublished":"2022-11-05T10:27:38+00:00","dateModified":"2023-03-02T09:07:49+00:00","breadcrumb":{"@id":"https:\/\/promopers.com\/privacy\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/promopers.com\/privacy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/promopers.com\/privacy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/promopers.com\/"},{"@type":"ListItem","position":2,"name":"Privacy Policy"}]},{"@type":"WebSite","@id":"https:\/\/promopers.com\/#website","url":"https:\/\/promopers.com\/","name":"X-Tool Services (Schweiz) AG","description":"Staff Solutions since 1999","publisher":{"@id":"https:\/\/promopers.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/promopers.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/promopers.com\/#organization","name":"promoPers","url":"https:\/\/promopers.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/promopers.com\/#\/schema\/logo\/image\/","url":"https:\/\/promopers.com\/wp-content\/uploads\/2022\/11\/logo.png","contentUrl":"https:\/\/promopers.com\/wp-content\/uploads\/2022\/11\/logo.png","width":62,"height":80,"caption":"promoPers"},"image":{"@id":"https:\/\/promopers.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/promotionspersonal\/"]}]}},"_links":{"self":[{"href":"https:\/\/promopers.com\/it\/wp-json\/wp\/v2\/pages\/3"}],"collection":[{"href":"https:\/\/promopers.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/promopers.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/promopers.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/promopers.com\/it\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":1,"href":"https:\/\/promopers.com\/it\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":842,"href":"https:\/\/promopers.com\/it\/wp-json\/wp\/v2\/pages\/3\/revisions\/842"}],"wp:attachment":[{"href":"https:\/\/promopers.com\/it\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}